{"id":3858,"date":"2018-09-18T06:18:57","date_gmt":"2018-09-18T06:18:57","guid":{"rendered":"https:\/\/andreamiriello.com\/\/\/obiettivi-intelligenti\/"},"modified":"2020-01-17T18:41:14","modified_gmt":"2020-01-17T18:41:14","slug":"obiettivi-intelligenti","status":"publish","type":"post","link":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","title":{"rendered":"Definire Obiettivi &#8220;Intelligenti&#8221; al Lavoro"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><b><i>Obiettivi SMART<\/i><\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nella psicologia del lavoro \u00e8 nota l&#8217;importanza di definire obiettivi chiari e stimolanti. Per esempio, questo aspetto \u00e8 critico nella gestione della prestazione, nell&#8217;orientamento professionale, nel marketing e nella vendita.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Senza obiettivi chiari le aziende e le persone si perdono.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Supponiamo che vuoi fare un viaggio ma non sai dove andare, prendi l&#8217;auto e parti senza una destinazione precisa. Cosa rischi? Rischi di perderti, vedere posti che non ti interessano, spendere tanti soldi per benzina, autostrada e alloggi dove dormire. Invece, se definisci una destinazione precisa puoi impostare sul navigatore il percorso pi\u00f9 breve, trovare in anticipo un alloggio a buon prezzo, pianificare quali attrazioni vedere in base ai tuoi interessi. Risultati: con una destinazione chiara risparmi tempo e denaro.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Prova a rispondere a questa domanda: \u201cCosa vuoi?\u201d<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Lasciami indovinare&#8230; non hai dato una risposta precisa.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Probabilmente hai risposto con frasi del tipo: \u201cvoglio essere felice\u201d, \u201cvoglio un lavoro\u201d, \u201cvoglio fare carriera\u201d.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Perch\u00e9 \u00e8 cos\u00ec difficile rispondere a questa domanda? Perch\u00e9 siamo spesso confusi, non sappiamo cosa vogliamo veramente o come ottenerlo.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Definire ci\u00f2 che realmente vuoi \u00e8 difficile, ma ne vale la pena. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Stabilire gli obiettivi e come raggiungerli \u00e8 un&#8217;abilit\u00e0 e un metodo di vitale importanza per il successo e il benessere. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Gli obiettivi ci forniscono una direzione, ci aiutano a sentirci motivati e ci permettono di raggiungere grandi risultati.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Un modo efficace per stabilire gli obiettivi \u00e8 il metodo SMARTS (Smith, 1994), il quale prevede di definire obiettivi specifici, misurabili, orientati all&#8217;azione e calendarizzati.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>S<\/b>pecific: Cosa voglio ottenere?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>M<\/b>easurable: Quanto voglio ottenere o guadagnare?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>A<\/b>ction oriented: Quali azioni devo mettere in pratica per ottenere ci\u00f2 che voglio?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>R<\/b>ealistic: E&#8217; raggiungibile? E&#8217; realistico? Ce la posso fare?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>T<\/b>ime-phased: Entro quando voglio raggiungere il mio obiettivo? Quando metto in atto ogni singola azione che mi serve per raggiungere il mio obiettivo?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>S<\/b>elf-determined: Questo obiettivo \u00e8 importante per me? Sono veramente interessato a raggiungerlo? E&#8217; stimolante? Lo voglio veramente?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Per chiarire meglio la differenza tra un obiettivo molto efficace e uno poco efficace leggi questi due esempi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Poco efficace: <\/b>\u201cVoglio aumentare le vendite e il mio reddito.\u201d \u00c8 troppo generale e vago.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Molto efficace (obiettivo SMARTS): \u201c<\/b>Voglio incrementare il fatturato delle vendite del 20% entro un anno (entro il 31\/12\/2017). Inizier\u00f2 aumentando il numero di chiamate a potenziali clienti da 50 a 100 al giorno. Poi incrementer\u00f2 il numero di presentazioni commerciali di persona da 10 a 15 alla settimana. \u00c8 fattibile? Si, devo solo lavorare un&#8217;ora in pi\u00f9 al giorno. \u00c8 importante guadagnare di pi\u00f9? Si, \u00e8 di fondamentale importanza.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Quest&#8217;ultimo esempio \u00e8 un obiettivo SMART, che in inglese significa intelligente, perch\u00e9 \u00e8 specifico, misurabile, orientato all&#8217;azione e calendarizzato, ovvero definito nel tempo anche con scadenze precise.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">In conclusione, stabilisci obiettivi chiari e precisi: non perdere tempo, sarai pi\u00f9 felice produttivo.<\/span><\/p>\n<p><strong>Dott. Andrea Miriello<br \/>\nPsicologo del lavoro e delle organizzazioni<br \/>\nConsulente, Formatore, Business Coach<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obiettivi SMART Nella psicologia del lavoro \u00e8 nota l&#8217;importanza di definire obiettivi chiari e stimolanti. Per esempio, questo aspetto \u00e8 critico nella gestione della prestazione, nell&#8217;orientamento professionale, nel marketing e nella vendita. Senza obiettivi chiari le aziende e le persone si perdono. Supponiamo che vuoi fare un viaggio ma non sai dove andare, prendi l&#8217;auto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[94],"tags":[138,139],"class_list":["post-3858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","tag-come-definire-i-propri-obiettivi","tag-definire-obiettivi-smart"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Definire Obiettivi &quot;Intelligenti&quot; al Lavoro - Andrea Miriello Psicologo del lavoro<\/title>\n<meta name=\"description\" content=\"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l&#039;articolo https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Definire Obiettivi &quot;Intelligenti&quot; al Lavoro - Andrea Miriello Psicologo del lavoro\" \/>\n<meta property=\"og:description\" content=\"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l&#039;articolo https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrea Miriello\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-18T06:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-17T18:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Miriello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Miriello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\"},\"author\":{\"name\":\"Andrea Miriello\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/#\\\/schema\\\/person\\\/aadcdf122adf42019f3c2722ec8a0301\"},\"headline\":\"Definire Obiettivi &#8220;Intelligenti&#8221; al Lavoro\",\"datePublished\":\"2018-09-18T06:18:57+00:00\",\"dateModified\":\"2020-01-17T18:41:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\"},\"wordCount\":470,\"image\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/andreamiriello.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/goal.jpg\",\"keywords\":[\"come definire i propri obiettivi\",\"definire obiettivi SMART\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\",\"url\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\",\"name\":\"Definire Obiettivi \\\"Intelligenti\\\" al Lavoro - Andrea Miriello Psicologo del lavoro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/andreamiriello.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/goal.jpg\",\"datePublished\":\"2018-09-18T06:18:57+00:00\",\"dateModified\":\"2020-01-17T18:41:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/#\\\/schema\\\/person\\\/aadcdf122adf42019f3c2722ec8a0301\"},\"description\":\"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l'articolo https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/andreamiriello.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/goal.jpg\",\"contentUrl\":\"https:\\\/\\\/andreamiriello.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/goal.jpg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/obiettivi-intelligenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Definire Obiettivi &#8220;Intelligenti&#8221; al Lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/\",\"name\":\"Andrea Miriello\",\"description\":\"Business Psychologist\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/#\\\/schema\\\/person\\\/aadcdf122adf42019f3c2722ec8a0301\",\"name\":\"Andrea Miriello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g\",\"caption\":\"Andrea Miriello\"},\"url\":\"https:\\\/\\\/andreamiriello.com\\\/it\\\/author\\\/crepuscolo_degli_idoli_5_2006\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Definire Obiettivi \"Intelligenti\" al Lavoro - Andrea Miriello Psicologo del lavoro","description":"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l'articolo https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","og_locale":"it_IT","og_type":"article","og_title":"Definire Obiettivi \"Intelligenti\" al Lavoro - Andrea Miriello Psicologo del lavoro","og_description":"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l'articolo https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","og_url":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","og_site_name":"Andrea Miriello","article_published_time":"2018-09-18T06:18:57+00:00","article_modified_time":"2020-01-17T18:41:14+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg","type":"image\/jpeg"}],"author":"Andrea Miriello","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Miriello","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#article","isPartOf":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/"},"author":{"name":"Andrea Miriello","@id":"https:\/\/andreamiriello.com\/it\/#\/schema\/person\/aadcdf122adf42019f3c2722ec8a0301"},"headline":"Definire Obiettivi &#8220;Intelligenti&#8221; al Lavoro","datePublished":"2018-09-18T06:18:57+00:00","dateModified":"2020-01-17T18:41:14+00:00","mainEntityOfPage":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/"},"wordCount":470,"image":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#primaryimage"},"thumbnailUrl":"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg","keywords":["come definire i propri obiettivi","definire obiettivi SMART"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","url":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","name":"Definire Obiettivi \"Intelligenti\" al Lavoro - Andrea Miriello Psicologo del lavoro","isPartOf":{"@id":"https:\/\/andreamiriello.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#primaryimage"},"image":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#primaryimage"},"thumbnailUrl":"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg","datePublished":"2018-09-18T06:18:57+00:00","dateModified":"2020-01-17T18:41:14+00:00","author":{"@id":"https:\/\/andreamiriello.com\/it\/#\/schema\/person\/aadcdf122adf42019f3c2722ec8a0301"},"description":"Come definire obiettivi chiari, precisi e misurabili. Definisci obiettivi SMART. Leggi l'articolo https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/","breadcrumb":{"@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#primaryimage","url":"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg","contentUrl":"https:\/\/andreamiriello.com\/wp-content\/uploads\/2018\/09\/goal.jpg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/andreamiriello.com\/it\/obiettivi-intelligenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andreamiriello.com\/it\/"},{"@type":"ListItem","position":2,"name":"Definire Obiettivi &#8220;Intelligenti&#8221; al Lavoro"}]},{"@type":"WebSite","@id":"https:\/\/andreamiriello.com\/it\/#website","url":"https:\/\/andreamiriello.com\/it\/","name":"Andrea Miriello","description":"Business Psychologist","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreamiriello.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/andreamiriello.com\/it\/#\/schema\/person\/aadcdf122adf42019f3c2722ec8a0301","name":"Andrea Miriello","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f0bce6824bf7f91bbb1d62b6a91b3d3319a75aea052e4dfe3a1cb7958640c0b?s=96&d=mm&r=g","caption":"Andrea Miriello"},"url":"https:\/\/andreamiriello.com\/it\/author\/crepuscolo_degli_idoli_5_2006\/"}]}},"_links":{"self":[{"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/posts\/3858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":0,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/media\/3914"}],"wp:attachment":[{"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreamiriello.com\/it\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}